{"id":395,"count":1,"description":"","link":"https:\/\/flighttime.de\/en\/category\/midsize-jets-en\/","name":"Midsize Jets","slug":"midsize-jets-en","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Midsize Jets Archive -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/flighttime.de\/en\/category\/midsize-jets-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Midsize Jets Archive\" \/>\n<meta property=\"og:url\" content=\"https:\/\/flighttime.de\/en\/category\/midsize-jets-en\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/flighttime.de\\\/en\\\/category\\\/midsize-jets-en\\\/\",\"url\":\"https:\\\/\\\/flighttime.de\\\/en\\\/category\\\/midsize-jets-en\\\/\",\"name\":\"Midsize Jets Archive -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/flighttime.de\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/flighttime.de\\\/en\\\/category\\\/midsize-jets-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/flighttime.de\\\/en\\\/category\\\/midsize-jets-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/flighttime.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Midsize Jets\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/flighttime.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/flighttime.de\\\/en\\\/\",\"name\":\"FlightTime\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/flighttime.de\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/flighttime.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/flighttime.de\\\/en\\\/#organization\",\"name\":\"FlightTime GmbH\",\"url\":\"https:\\\/\\\/flighttime.de\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/flighttime.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/flighttime.de\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/placeholder_img.png\",\"contentUrl\":\"https:\\\/\\\/flighttime.de\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/placeholder_img.png\",\"width\":326,\"height\":203,\"caption\":\"FlightTime GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/flighttime.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/FlightTime.gmbh\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/flighttime-gmbh\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Midsize Jets Archive -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/flighttime.de\/en\/category\/midsize-jets-en\/","og_locale":"en_US","og_type":"article","og_title":"Midsize Jets Archive","og_url":"https:\/\/flighttime.de\/en\/category\/midsize-jets-en\/","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/flighttime.de\/en\/category\/midsize-jets-en\/","url":"https:\/\/flighttime.de\/en\/category\/midsize-jets-en\/","name":"Midsize Jets Archive -","isPartOf":{"@id":"https:\/\/flighttime.de\/en\/#website"},"breadcrumb":{"@id":"https:\/\/flighttime.de\/en\/category\/midsize-jets-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/flighttime.de\/en\/category\/midsize-jets-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/flighttime.de\/en\/"},{"@type":"ListItem","position":2,"name":"Midsize Jets"}]},{"@type":"WebSite","@id":"https:\/\/flighttime.de\/en\/#website","url":"https:\/\/flighttime.de\/en\/","name":"FlightTime","description":"","publisher":{"@id":"https:\/\/flighttime.de\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/flighttime.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/flighttime.de\/en\/#organization","name":"FlightTime GmbH","url":"https:\/\/flighttime.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/flighttime.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/flighttime.de\/wp-content\/uploads\/2024\/06\/placeholder_img.png","contentUrl":"https:\/\/flighttime.de\/wp-content\/uploads\/2024\/06\/placeholder_img.png","width":326,"height":203,"caption":"FlightTime GmbH"},"image":{"@id":"https:\/\/flighttime.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FlightTime.gmbh","https:\/\/www.linkedin.com\/company\/flighttime-gmbh\/"]}]}},"_links":{"self":[{"href":"https:\/\/flighttime.de\/en\/wp-json\/wp\/v2\/categories\/395","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/flighttime.de\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/flighttime.de\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/flighttime.de\/en\/wp-json\/wp\/v2\/posts?categories=395"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}